{"id":1824,"date":"2026-05-20T13:32:17","date_gmt":"2026-05-20T13:32:17","guid":{"rendered":"https:\/\/mbt.travelblox.eu\/?page_id=1824"},"modified":"2026-07-09T15:00:26","modified_gmt":"2026-07-09T15:00:26","slug":"a-propos-du-mont-blanc-trail","status":"publish","type":"page","link":"https:\/\/mbt.travelblox.eu\/en\/a-propos-du-mont-blanc-trail\/","title":{"rendered":"About the Mont Blanc Trail"},"content":{"rendered":"<div class=\"tb-header tb-block align-center background-dark pattern-none variant-none\" id=\"header\" data-fallback-background=\"https:\/\/mbt.travelblox.eu\/wp-content\/uploads\/sites\/56\/2024\/10\/MBT24_RoyMosterd_WR-7230839-scaled-e1762183972908.jpg\" style=\"background-image: linear-gradient(rgba(0, 0, 0, 0.4), rgba(0, 0, 0, 0.4)), url('https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/MBT24_RoyMosterd_WR-7230839-scaled-e1762183972908.jpg.webp'); background-position:50% 50%;\" data-smush-webp-fallback=\"{&quot;bg-image&quot;:&quot; linear-gradient(rgba(0, 0, 0, 0.4), rgba(0, 0, 0, 0.4)), url(&#039;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/MBT24_RoyMosterd_WR-7230839-scaled-e1762183972908.jpg&#039;)&quot;}\">\n        \n    <div class=\"tb-header-foreground\">\n        <div class=\"inner-block\">\n\n            <div class=\"main-part\">\n                <div class=\"text-part\">\n                                                                                            <h1>\t<span class=\"tb-logo\"  style=\"-webkit-mask-image: url(https:\/\/mbt.travelblox.eu\/wp-content\/uploads\/sites\/56\/2024\/10\/TMBT_Logo_def_NL_white-1024x1024.png); mask-image: url(https:\/\/mbt.travelblox.eu\/wp-content\/uploads\/sites\/56\/2024\/10\/TMBT_Logo_def_NL_white-1024x1024.png)\">\n\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/TMBT_Logo_def_NL_white-1024x1024.png.webp' width='1024' height='1024' alt='The Mont Blanc Trail logo' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/TMBT_Logo_def_NL_white-1024x1024.png.webp 1024w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/TMBT_Logo_def_NL_white-300x300.png.webp 300w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/TMBT_Logo_def_NL_white-150x150.png.webp 150w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/TMBT_Logo_def_NL_white-768x768.png.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/TMBT_Logo_def_NL_white-1536x1536.png.webp 1536w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/TMBT_Logo_def_NL_white-12x12.png.webp 12w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/TMBT_Logo_def_NL_white.png.webp 1677w' sizes='(max-width: 1024px) 100vw, 1024px' title='The Mont Blanc Trail' loading='lazy' data-smush-webp-fallback='{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/TMBT_Logo_def_NL_white-1024x1024.png&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/TMBT_Logo_def_NL_white-1024x1024.png 1024w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/TMBT_Logo_def_NL_white-300x300.png 300w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/TMBT_Logo_def_NL_white-150x150.png 150w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/TMBT_Logo_def_NL_white-768x768.png 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/TMBT_Logo_def_NL_white-1536x1536.png 1536w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/TMBT_Logo_def_NL_white-12x12.png 12w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/TMBT_Logo_def_NL_white.png 1677w&quot;}'>\n\t<\/span>\n<\/h1>\n                                                                                        <h2 class=\"tb-subtitle\">\t<div class=\"translation-block\"><p>The team and the story behind the Mont Blanc Trail<\/p><\/div>\n\t<\/h2>\n                                                                                                                    <\/div>\n            <\/div>\n\n                    <\/div>\n    <\/div>\n\n    \n    \n    \n<\/div>\n\n\n<div class=\"tb-textimage2 tb-block align-left background-light pattern-none variant-text_first tb-collapsible-margins\" id=\"textimage2\">\n\t<div class=\"inner-block tb-fade-in\">\n\n\t\t\n\t\t\t\t<div class=\"tb-columns\">\n\t\t\t<div class=\"tb-column\">\n\t\t\t\t<div class=\"tb-text-part\">\n\t\t\t\t\t<h2>AN AUTHENTIC ADVENTURE THROUGH FRANCE, ITALY, AND SWITZERLAND<\/h2>\n\t\t\t\t\t\t<div class=\"translation-block tb-wysiwyg-part\"><p>At <strong>Mont Blanc Trail<\/strong>, we believe that to create an authentic journey, you need to step off the beaten path to <strong>discover the wild heart of a country<\/strong>. From the very beginning of this project, we partnered with local experts to develop a unique itinerary around Mont Blanc. During this trek, you won't just pass through <strong>one country, but three<\/strong>! You'll experience the beauty of the Alps, the cultures of these three countries, and the most magical spots of this renowned trek.<\/p>\n<p>The story began in 2022 when our team set out to do the Tour du Mont Blanc in search of a <strong>5-day itinerary focusing on the most stunning hikes of this trek.<\/strong> We were immediately captivated by the breathtaking landscapes and the hospitality of the locals, who have since become our loyal partners. Even today, they welcome you with open arms in campgrounds and refuges to offer you a total immersion experience.<\/p>\n<p><strong>Together, we brought the Mont Blanc Trail to life.<\/strong><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tb-buttons-part\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/themontblanctrail.com\/en\"  target=\"_blank\" class=\"tb-button\">\n\t\t\tDiscover the Mont Blanc Trail\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"tb-column\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-768x586.jpg.webp' width='768' height='586' alt='3 people walking together on the Mont Blanc Trail Mont Blanc Circuit' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-768x586.jpg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-300x229.jpg.webp 300w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-1024x782.jpg.webp 1024w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-1536x1173.jpg.webp 1536w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-2048x1563.jpg.webp 2048w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-16x12.jpg.webp 16w' sizes=\"auto, (max-width: 768px) 100vw, 768px\" style='object-position:50% 50%' loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-768x586.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-768x586.jpg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-300x229.jpg 300w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-1024x782.jpg 1024w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-1536x1173.jpg 1536w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-2048x1563.jpg 2048w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/MBT24_RoyMosterd_WR-7250370-scaled-e1730126879820-16x12.jpg 16w&quot;}\">\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"tb-team tb-block align-center background-dark pattern-none variant-none tb-collapsible-margins\" id=\"team\">\n\t<div class=\"inner-block tb-fade-in tb-fade-in--subtle\">\n\t\t<div class=\"text-part\">\n\t\t\t<h2>WHO'S BEHIND THIS PROJECT?<\/h2>\n\t\t\t\t<div class=\"translation-block\"><p>With our French, Swiss, and Italian partners, we work year-round on this adventure, with one goal in mind: to offer you the most authentic travel experience possible. A trek you won\u2019t forget anytime soon and that might even change your perspective on travel.<\/p><\/div>\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t<div class=\"inner-block-full-width has-tb-carousel\" >\n\t\t<div class=\"tb-carousel-container\">\n\t\t\t<div class=\"entries tb-cards\" data-slider-first=\"1\">\n\t\t\t\t\t\t\t\t\t<div class=\"tb-card entry\" style=\"background-image: url('https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/11\/Agathe-1024x1024.jpg.webp')\" data-smush-webp-fallback=\"{&quot;bg-image&quot;:&quot; url(&#039;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/11\\\/Agathe-1024x1024.jpg&#039;)&quot;}\">\n\t\t\t\t<label for=\"tb-team-read-more-block_s56__p1824__team-0\" class=\"tb-team__card-label\">\n\t\t\t\t\t<div class=\"overlay\"><\/div>\n\t\t\t\t\t<div class=\"overlay overlay--extra\"><\/div>\n\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t<div class=\"tb-team__card-titles\">\n\t\t\t\t\t\t\t<h3>Agathe<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Coordinator<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"extra-content\">\n\t\t\t\t\t\t\t\t<p>Agathe designs and coordinates the project from A to Z.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<input type=\"checkbox\" class=\"tb-team__card-checkbox\" id=\"tb-team-read-more-block_s56__p1824__team-0\">\n\t\t\t\t<\/label>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"tb-card entry\" style=\"background-image: url('https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/11\/Louise-1024x1024.jpg.webp')\" data-smush-webp-fallback=\"{&quot;bg-image&quot;:&quot; url(&#039;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/11\\\/Louise-1024x1024.jpg&#039;)&quot;}\">\n\t\t\t\t<label for=\"tb-team-read-more-block_s56__p1824__team-1\" class=\"tb-team__card-label\">\n\t\t\t\t\t<div class=\"overlay\"><\/div>\n\t\t\t\t\t<div class=\"overlay overlay--extra\"><\/div>\n\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t<div class=\"tb-team__card-titles\">\n\t\t\t\t\t\t\t<h3>Louise<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Travel expert<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"extra-content\">\n\t\t\t\t\t\t\t\t<p>Louise answers all your questions about the project.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<input type=\"checkbox\" class=\"tb-team__card-checkbox\" id=\"tb-team-read-more-block_s56__p1824__team-1\">\n\t\t\t\t<\/label>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"tb-card entry\" style=\"background-image: url('https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7240137-1024x768.jpg.webp')\" data-smush-webp-fallback=\"{&quot;bg-image&quot;:&quot; url(&#039;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7240137-1024x768.jpg&#039;)&quot;}\">\n\t\t\t\t<label for=\"tb-team-read-more-block_s56__p1824__team-2\" class=\"tb-team__card-label\">\n\t\t\t\t\t<div class=\"overlay\"><\/div>\n\t\t\t\t\t<div class=\"overlay overlay--extra\"><\/div>\n\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t<div class=\"tb-team__card-titles\">\n\t\t\t\t\t\t\t<h3>Our team<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>the Rangers<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"extra-content\">\n\t\t\t\t\t\t\t\t<p>They handle all the logistics on site.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<input type=\"checkbox\" class=\"tb-team__card-checkbox\" id=\"tb-team-read-more-block_s56__p1824__team-2\">\n\t\t\t\t<\/label>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"tb-card entry\" style=\"background-image: url('https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/MBT24_RoyMosterd_WR-7220711-768x1024.jpg.webp')\" data-smush-webp-fallback=\"{&quot;bg-image&quot;:&quot; url(&#039;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/MBT24_RoyMosterd_WR-7220711-768x1024.jpg&#039;)&quot;}\">\n\t\t\t\t<label for=\"tb-team-read-more-block_s56__p1824__team-3\" class=\"tb-team__card-label\">\n\t\t\t\t\t<div class=\"overlay\"><\/div>\n\t\t\t\t\t<div class=\"overlay overlay--extra\"><\/div>\n\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t<div class=\"tb-team__card-titles\">\n\t\t\t\t\t\t\t<h3>Our partners<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Locals<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"extra-content\">\n\t\t\t\t\t\t\t\t<p>They welcome you in lodges and campsites during your stay.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<input type=\"checkbox\" class=\"tb-team__card-checkbox\" id=\"tb-team-read-more-block_s56__p1824__team-3\">\n\t\t\t\t<\/label>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"tb-carousel-nav\">\n\t\t<div class=\"dots\">\n\t\t\t<div class=\"dot active\"><\/div>\n\t\t\t<div class=\"dot\"><\/div>\n\t\t\t<div class=\"dot\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"arrows\">\n\t\t\t<div class=\"prev disabled\">\n\t\t\t\t<span><i class=\"fa fa-chevron-left\"><\/i><\/span>\n\t\t\t<\/div>\n\t\t\t<div class=\"next\">\n\t\t\t\t<span><i class=\"fa fa-chevron-right\"><\/i><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t<\/div>\n\n\n<div class=\"tb-colcompare tb-block align-center background-light pattern-none variant-cards tb-collapsible-margins\" id=\"colcompare\">\n\t<div class=\"inner-block tb-fade-in tb-fade-in--subtle\">\n\t\t<div class=\"text-part\">\n\t\t\t<h2>Why travel with the Mont Blanc Trail?<\/h2>\n\t\t\t\t<div class=\"translation-block\"><\/div>\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t<div class=\"inner-block-full-width has-tb-carousel tb-justified\" >\n\t\t<div class=\"tb-carousel-container\">\n\t\t\t<div class=\"entries tb-cards\" data-slider-first=\"1\">\n\t\t\t\t\t\t\t\t\t<div class=\"tb-card entry tb-fade-in tb-fade-in--subtle\">\n\t\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933-768x894.jpeg.webp' width='768' height='894' alt='Trek to Mont Blanc Mont Blanc Circuit' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933-768x894.jpeg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933-258x300.jpeg.webp 258w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933-879x1024.jpeg.webp 879w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933-10x12.jpeg.webp 10w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933.jpeg.webp 979w' sizes=\"auto, (max-width: 768px) 100vw, 768px\" style='object-position:50% 50%' loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933-768x894.jpeg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933-768x894.jpeg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933-258x300.jpeg 258w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933-879x1024.jpeg 879w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933-10x12.jpeg 10w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_050-Large-e1761567071933.jpeg 979w&quot;}\">\t\t\t\t<\/div>\n\t\t\t\t<div class=\"tb-card-content text-part\">\n\t\t\t\t\t\t\t\t\t\t\t<h5> 5-DAY ITINERARY<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"translation-block\"><p>The hiking route we\u2019ve mapped out is a condensed version of the <strong>most beautiful spots in the Tour of Mont Blanc<\/strong>. We\u2019ve selected the most stunning locations and the best places to spend the night, to give you, in just one week, the very essence of this magnificent trek.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"tb-card entry tb-fade-in tb-fade-in--subtle\">\n\t\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_030-Large-768x511.jpeg.webp' width='768' height='511' alt='Mont Blanc Round Trip Hike' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_030-Large-768x511.jpeg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_030-Large-300x200.jpeg.webp 300w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_030-Large-1024x682.jpeg.webp 1024w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_030-Large-18x12.jpeg.webp 18w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/TheMontBlancTrail_Thru-Hiking_030-Large.jpeg.webp 1280w' sizes=\"auto, (max-width: 768px) 100vw, 768px\" style='object-position:50% 50%' loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_030-Large-768x511.jpeg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_030-Large-768x511.jpeg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_030-Large-300x200.jpeg 300w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_030-Large-1024x682.jpeg 1024w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_030-Large-18x12.jpeg 18w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/TheMontBlancTrail_Thru-Hiking_030-Large.jpeg 1280w&quot;}\">\t\t\t\t<\/div>\n\t\t\t\t<div class=\"tb-card-content text-part\">\n\t\t\t\t\t\t\t\t\t\t\t<h5> ABORDABLE<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"translation-block\"><p>Our mission is to provide you with maximum adventure for a fair price. We achieve this by <strong>developing the trek from A to Z<\/strong> and forming partnerships with locals.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"tb-card entry tb-fade-in tb-fade-in--subtle\">\n\t\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR--768x1024.jpg.webp' width='768' height='1024' alt='The Mont Blanc Trail - tour du mont blanc' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR--768x1024.jpg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR--225x300.jpg.webp 225w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR--1152x1536.jpg.webp 1152w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR--1536x2048.jpg.webp 1536w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR--9x12.jpg.webp 9w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR--scaled.jpg.webp 1920w' sizes=\"auto, (max-width: 768px) 100vw, 768px\" loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR--768x1024.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR--768x1024.jpg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR--225x300.jpg 225w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR--1152x1536.jpg 1152w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR--1536x2048.jpg 1536w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR--9x12.jpg 9w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR--scaled.jpg 1920w&quot;}\">\t\t\t\t<\/div>\n\t\t\t\t<div class=\"tb-card-content text-part\">\n\t\t\t\t\t\t\t\t\t\t\t<h5> FLAWLESS ORGANIZATION<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"translation-block\"><p>All practical aspects are taken care of by us, so you can <strong>make the most of it.<\/strong> Our travelers give us an average rating of 4.9 out of 5.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"tb-card entry tb-fade-in tb-fade-in--subtle\">\n\t\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-768x748.jpg.webp' width='768' height='748' alt='The Mont Blanc Trail - tour of Mont Blanc Mont Blanc Round Tour' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-768x748.jpg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-300x292.jpg.webp 300w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-1024x997.jpg.webp 1024w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-1536x1496.jpg.webp 1536w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-12x12.jpg.webp 12w' sizes=\"auto, (max-width: 768px) 100vw, 768px\" style='object-position:50% 50%' loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-768x748.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-768x748.jpg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-300x292.jpg 300w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-1024x997.jpg 1024w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-1536x1496.jpg 1536w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7220518-scaled-e1761561850286-12x12.jpg 12w&quot;}\">\t\t\t\t<\/div>\n\t\t\t\t<div class=\"tb-card-content text-part\">\n\t\t\t\t\t\t\t\t\t\t\t<h5> RESPONSIBLE<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"translation-block\"><p>By supporting local projects on site and minimizing the CO\u2082 emissions from our travels, we aim to <strong>create a positive impact through your adventure.<\/strong><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"tb-carousel-nav\">\n\t\t<div class=\"dots\">\n\t\t\t<div class=\"dot active\"><\/div>\n\t\t\t<div class=\"dot\"><\/div>\n\t\t\t<div class=\"dot\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"arrows\">\n\t\t\t<div class=\"prev disabled\">\n\t\t\t\t<span><i class=\"fa fa-chevron-left\"><\/i><\/span>\n\t\t\t<\/div>\n\t\t\t<div class=\"next\">\n\t\t\t\t<span><i class=\"fa fa-chevron-right\"><\/i><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t<\/div>\n\n\n\n<div class=\"tb-textimage1 tb-block align-center background-light pattern-none variant-none tb-collapsible-margins\" id=\"textimage1\">\n\t<div class=\"inner-block tb-fade-in tb-fade-in--subtle\">\n\n\t\t\n\t\t<div class=\"text-part\">\n\t\t\t<h2>THE MONT BLANC TRAIL, A CONCEPT BY TRAVELBASE<\/h2>\n\t\t\t\t<div class=\"translation-block\"><p>The <strong>Mont Blanc Trail<\/strong> is not an isolated project; it\u2019s a concept by <strong>Travelbase<\/strong>, an experienced travel agency that sends over <strong>50,000 people<\/strong> on adventures around the world each year. With more than <strong>10 years of experience<\/strong> in active and adventure travel, Travelbase ensures solid organization, close collaboration with local partners, and authentic experiences.<\/p><\/div>\n\t\t\t<\/div>\n\t<\/div>\n\t<div class=\"inner-block\">\n\t\t\t\t\t\t\t\t\t<div class=\"tb-video-part\">\n\t\t\t\t\t<iframe src=\"https:\/\/iframe.mediadelivery.net\/embed\/295792\/51da9b20-50cb-4a83-a4ac-61a4a47e3a43?autoplay=true&#038;preload=true&#038;loop=true&#038;responsive=true&#038;muted=true\" allow=\"accelerometer;gyroscope;encrypted-media;picture-in-picture;autoplay;muted;\" allowfullscreen=\"true\" style=\"border: none;\" loading=\"lazy\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"inner-block tb-fade-in tb-fade-in--subtle\">\n\t\t\t<div class=\"text-part\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tb-buttons-part\">\n\t\t\t\t\t\t\t\t<a href=\"http:\/\/travelbase.world\"  target=\"_blank\" class=\"tb-button\">\n\t\t\tTravelbase website\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n\n<div class=\"tb-gallery tb-block align-center background-light pattern-none variant-grid\" id=\"gallery\">\n\t<div class=\"tb-gallery__inner\">\n\t\t<div class=\"desktop tb-has-popup-content\">\n\t\t\t\t\t\t\t<ul class=\"tb-gallery-grid\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"slide\">\n\t\t\t\t\t\t\t\t<div class=\"tb-popup-trigger\">\n\t\t\t\t\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-scaled.jpg.webp' width='2560' height='1920' alt='The Mont Blanc Trail - tour du mont blanc' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-scaled.jpg.webp 2560w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-300x225.jpg.webp 300w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-1024x768.jpg.webp 1024w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-768x576.jpg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-1536x1152.jpg.webp 1536w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-2048x1536.jpg.webp 2048w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-16x12.jpg.webp 16w' sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" style='object-position:50% 50%' loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-scaled.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-scaled.jpg 2560w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-300x225.jpg 300w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-1024x768.jpg 1024w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-768x576.jpg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-1536x1152.jpg 1536w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-2048x1536.jpg 2048w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-16x12.jpg 16w&quot;}\">\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"slide\">\n\t\t\t\t\t\t\t\t<div class=\"tb-popup-trigger\">\n\t\t\t\t\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7240197-scaled-e1762183722181.jpg.webp' width='2500' height='1875' alt='The Mont Blanc Trail - tour of Mont Blanc Mont Blanc Round Tour' style='object-position:50% 50%' loading='lazy' decoding='async' data-smush-webp-fallback='{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7240197-scaled-e1762183722181.jpg&quot;}'>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"slide\">\n\t\t\t\t\t\t\t\t<div class=\"tb-popup-trigger\">\n\t\t\t\t\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande.jpeg.webp' width='1280' height='852' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande.jpeg.webp 1280w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-300x200.jpeg.webp 300w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-1024x682.jpeg.webp 1024w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-768x511.jpeg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-18x12.jpeg.webp 18w' sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande.jpeg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande.jpeg 1280w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-300x200.jpeg 300w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-1024x682.jpeg 1024w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-768x511.jpeg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-18x12.jpeg 18w&quot;}\">\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<div class=\"tb-popup tb-popup--open-clicked-image\">\n\t\t\t\t<div class=\"tb-gallery-popup\">\n\t\t\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t\t\t\t\t<div class=\"inner-block-full-width has-tb-carousel tb-carousel-slider\" >\n\t\t<div class=\"tb-carousel-container\">\n\t\t\t<div class=\"entries tb-cards\" data-slider-first=\"2\">\n\t\t\t\t\t\t\t<div class=\"entry\">\n\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t<figure>\n\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-scaled.jpg.webp' width='2560' height='1920' alt='The Mont Blanc Trail - tour du mont blanc' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-scaled.jpg.webp 2560w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-300x225.jpg.webp 300w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-1024x768.jpg.webp 1024w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-768x576.jpg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-1536x1152.jpg.webp 1536w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-2048x1536.jpg.webp 2048w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-16x12.jpg.webp 16w' sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" style='object-position:50% 50%' loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-scaled.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-scaled.jpg 2560w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-300x225.jpg 300w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-1024x768.jpg 1024w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-768x576.jpg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-1536x1152.jpg 1536w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-2048x1536.jpg 2048w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-16x12.jpg 16w&quot;}\">\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<div class=\"entry\">\n\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t<figure>\n\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7240197-scaled-e1762183722181.jpg.webp' width='2500' height='1875' alt='The Mont Blanc Trail - tour of Mont Blanc Mont Blanc Round Tour' style='object-position:50% 50%' loading='lazy' decoding='async' data-smush-webp-fallback='{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7240197-scaled-e1762183722181.jpg&quot;}'>\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<div class=\"entry\">\n\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t<figure>\n\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande.jpeg.webp' width='1280' height='852' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande.jpeg.webp 1280w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-300x200.jpeg.webp 300w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-1024x682.jpeg.webp 1024w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-768x511.jpeg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-18x12.jpeg.webp 18w' sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande.jpeg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande.jpeg 1280w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-300x200.jpeg 300w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-1024x682.jpeg 1024w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-768x511.jpeg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-18x12.jpeg 18w&quot;}\">\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"tb-carousel-nav\">\n\t\t<div class=\"dots\">\n\t\t\t<div class=\"dot active\"><\/div>\n\t\t\t<div class=\"dot\"><\/div>\n\t\t\t<div class=\"dot\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"arrows\">\n\t\t\t<div class=\"prev disabled\">\n\t\t\t\t<span><i class=\"fa fa-chevron-left\"><\/i><\/span>\n\t\t\t<\/div>\n\t\t\t<div class=\"next\">\n\t\t\t\t<span><i class=\"fa fa-chevron-right\"><\/i><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"mobile\">\n\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t\t\t<div class=\"inner-block-full-width has-tb-carousel tb-carousel-slider\" >\n\t\t<div class=\"tb-carousel-container\">\n\t\t\t<div class=\"entries tb-cards\" data-slider-first=\"0\">\n\t\t\t\t\t\t\t<div class=\"entry\">\n\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t<figure>\n\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-768x576.jpg.webp' width='768' height='576' alt='The Mont Blanc Trail - tour du mont blanc' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-768x576.jpg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-300x225.jpg.webp 300w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-1024x768.jpg.webp 1024w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-1536x1152.jpg.webp 1536w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-2048x1536.jpg.webp 2048w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7260559-16x12.jpg.webp 16w' sizes=\"auto, (max-width: 768px) 100vw, 768px\" style='object-position:50% 50%' loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-768x576.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-768x576.jpg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-300x225.jpg 300w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-1024x768.jpg 1024w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-1536x1152.jpg 1536w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-2048x1536.jpg 2048w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7260559-16x12.jpg 16w&quot;}\">\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<div class=\"entry\">\n\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t<figure>\n\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7240197-768x576.jpg.webp' width='768' height='576' alt='The Mont Blanc Trail - tour of Mont Blanc Mont Blanc Round Tour' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7240197-768x576.jpg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7240197-300x225.jpg.webp 300w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7240197-1024x768.jpg.webp 1024w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7240197-1536x1152.jpg.webp 1536w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7240197-2048x1536.jpg.webp 2048w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2025\/09\/MBT24_RoyMosterd_WR-7240197-16x12.jpg.webp 16w' sizes=\"auto, (max-width: 768px) 100vw, 768px\" style='object-position:50% 50%' loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7240197-768x576.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7240197-768x576.jpg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7240197-300x225.jpg 300w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7240197-1024x768.jpg 1024w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7240197-1536x1152.jpg 1536w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7240197-2048x1536.jpg 2048w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2025\\\/09\\\/MBT24_RoyMosterd_WR-7240197-16x12.jpg 16w&quot;}\">\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<div class=\"entry\">\n\t\t\t<div class=\"tb-image-part\">\n\t\t\t\t<figure>\n\t\t\t\t\t<img src='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-768x511.jpeg.webp' width='768' height='511' srcset='https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-768x511.jpeg.webp 768w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-300x200.jpeg.webp 300w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-1024x682.jpeg.webp 1024w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-18x12.jpeg.webp 18w, https:\/\/mbt.travelblox.eu\/wp-content\/smush-webp\/sites\/56\/2024\/10\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande.jpeg.webp 1280w' sizes=\"auto, (max-width: 768px) 100vw, 768px\" loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-768x511.jpeg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-768x511.jpeg 768w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-300x200.jpeg 300w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-1024x682.jpeg 1024w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande-18x12.jpeg 18w, https:\\\/\\\/mbt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/10\\\/20240628-TMBavecTravelbase-MarineCLAUDEPhotographe-30-Grande.jpeg 1280w&quot;}\">\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"tb-carousel-nav\">\n\t\t<div class=\"dots\">\n\t\t\t<div class=\"dot active\"><\/div>\n\t\t\t<div class=\"dot\"><\/div>\n\t\t\t<div class=\"dot\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"arrows\">\n\t\t\t<div class=\"prev disabled\">\n\t\t\t\t<span><i class=\"fa fa-chevron-left\"><\/i><\/span>\n\t\t\t<\/div>\n\t\t\t<div class=\"next\">\n\t\t\t\t<span><i class=\"fa fa-chevron-right\"><\/i><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"tb-textimage2 tb-block align-left background-light pattern-none variant-text_first tb-collapsible-margins\" id=\"textimage2-1\">\n\t<div class=\"inner-block tb-fade-in\">\n\n\t\t\n\t\t\t\t<div class=\"tb-columns\">\n\t\t\t<div class=\"tb-column\">\n\t\t\t\t<div class=\"tb-text-part\">\n\t\t\t\t\t<h2>TRAVEL WITH A POSITIVE IMPACT<\/h2>\n\t\t\t\t\t\t<div class=\"translation-block tb-wysiwyg-part\"><p>We believe in travel with a positive impact. Through our own <strong>Butterfly Foundation<\/strong>, we support dozens of social and ecological projects around the world.<\/p>\n<p>We collaborate with several pioneers in nature conservation across Europe. These organizations are dedicated to protecting endangered species, fragile ecosystems, and preserving national parks in the areas our treks pass through.<\/p>\n<p>By traveling with us, you support projects that truly make a difference.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tb-buttons-part\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/butterfly-foundation.org\/en\/action\/\"  target=\"_blank\" class=\"tb-button\">\n\t\t\tButterfly foundation\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"tb-column\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tb-video-part\">\n\t\t\t\t\t\t\t<iframe src=\"https:\/\/iframe.mediadelivery.net\/embed\/295792\/e782675e-6293-4c8b-815e-908fc62d8c5a?autoplay=true&#038;preload=true&#038;loop=true&#038;responsive=true&#038;muted=true\" allow=\"accelerometer;gyroscope;encrypted-media;picture-in-picture;autoplay;muted;\" allowfullscreen=\"true\" style=\"border: none;\" loading=\"lazy\"><\/iframe>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":136,"featured_media":1251,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1824","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":{"page_package_ids":"","is_main_package_page":false,"additional_linked_packages":[],"feed_page_to_atlas":true},"_links":{"self":[{"href":"https:\/\/mbt.travelblox.eu\/en\/wp-json\/wp\/v2\/pages\/1824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mbt.travelblox.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mbt.travelblox.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mbt.travelblox.eu\/en\/wp-json\/wp\/v2\/users\/136"}],"replies":[{"embeddable":true,"href":"https:\/\/mbt.travelblox.eu\/en\/wp-json\/wp\/v2\/comments?post=1824"}],"version-history":[{"count":19,"href":"https:\/\/mbt.travelblox.eu\/en\/wp-json\/wp\/v2\/pages\/1824\/revisions"}],"predecessor-version":[{"id":2068,"href":"https:\/\/mbt.travelblox.eu\/en\/wp-json\/wp\/v2\/pages\/1824\/revisions\/2068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mbt.travelblox.eu\/en\/wp-json\/wp\/v2\/media\/1251"}],"wp:attachment":[{"href":"https:\/\/mbt.travelblox.eu\/en\/wp-json\/wp\/v2\/media?parent=1824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}